{"id":7676,"date":"2019-07-10T12:56:43","date_gmt":"2019-07-10T10:56:43","guid":{"rendered":"https:\/\/restauranterodas.es\/privacy-policy\/"},"modified":"2026-05-04T13:39:10","modified_gmt":"2026-05-04T11:39:10","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/restauranterodas.es\/en\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<p>[pdrgpd-politica-privacidad]<\/p>\n\r\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7676","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - Restaurante Praia de Rodas, Illas C\u00edes<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - Restaurante Praia de Rodas, Illas C\u00edes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/restauranterodas.es\/en\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurante Praia de Rodas, Illas C\u00edes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pg\/LaCandelaRestauranteVigo\/about\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T11:39:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - Restaurante Praia de Rodas, Illas C\u00edes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/#website\"},\"datePublished\":\"2019-07-10T10:56:43+00:00\",\"dateModified\":\"2026-05-04T11:39:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/restauranterodas.es\\\/en\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/\",\"name\":\"Cocina Fusi\u00f3n Vigo - Restaurante Candela\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/#organization\",\"name\":\"La Candela Cocina Fusi\u00f3n\",\"url\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/restauranterodas.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-fixed.png\",\"contentUrl\":\"https:\\\/\\\/restauranterodas.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-fixed.png\",\"width\":99,\"height\":32,\"caption\":\"La Candela Cocina Fusi\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/restauranterodas.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pg\\\/LaCandelaRestauranteVigo\\\/about\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - Restaurante Praia de Rodas, Illas C\u00edes","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Privacy Policy - Restaurante Praia de Rodas, Illas C\u00edes","og_url":"https:\/\/restauranterodas.es\/en\/privacy-policy\/","og_site_name":"Restaurante Praia de Rodas, Illas C\u00edes","article_publisher":"https:\/\/www.facebook.com\/pg\/LaCandelaRestauranteVigo\/about\/","article_modified_time":"2026-05-04T11:39:10+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/restauranterodas.es\/en\/privacy-policy\/","url":"https:\/\/restauranterodas.es\/en\/privacy-policy\/","name":"Privacy Policy - Restaurante Praia de Rodas, Illas C\u00edes","isPartOf":{"@id":"https:\/\/restauranterodas.es\/en\/#website"},"datePublished":"2019-07-10T10:56:43+00:00","dateModified":"2026-05-04T11:39:10+00:00","breadcrumb":{"@id":"https:\/\/restauranterodas.es\/en\/privacy-policy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/restauranterodas.es\/en\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/restauranterodas.es\/en\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/restauranterodas.es\/en\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/restauranterodas.es\/en\/#website","url":"https:\/\/restauranterodas.es\/en\/","name":"Cocina Fusi\u00f3n Vigo - Restaurante Candela","description":"","publisher":{"@id":"https:\/\/restauranterodas.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/restauranterodas.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/restauranterodas.es\/en\/#organization","name":"La Candela Cocina Fusi\u00f3n","url":"https:\/\/restauranterodas.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/restauranterodas.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/restauranterodas.es\/wp-content\/uploads\/2019\/07\/logo-fixed.png","contentUrl":"https:\/\/restauranterodas.es\/wp-content\/uploads\/2019\/07\/logo-fixed.png","width":99,"height":32,"caption":"La Candela Cocina Fusi\u00f3n"},"image":{"@id":"https:\/\/restauranterodas.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pg\/LaCandelaRestauranteVigo\/about\/"]}]}},"_links":{"self":[{"href":"https:\/\/restauranterodas.es\/en\/wp-json\/wp\/v2\/pages\/7676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/restauranterodas.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/restauranterodas.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/restauranterodas.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/restauranterodas.es\/en\/wp-json\/wp\/v2\/comments?post=7676"}],"version-history":[{"count":1,"href":"https:\/\/restauranterodas.es\/en\/wp-json\/wp\/v2\/pages\/7676\/revisions"}],"predecessor-version":[{"id":40269,"href":"https:\/\/restauranterodas.es\/en\/wp-json\/wp\/v2\/pages\/7676\/revisions\/40269"}],"wp:attachment":[{"href":"https:\/\/restauranterodas.es\/en\/wp-json\/wp\/v2\/media?parent=7676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}